{"id":46106,"date":"2023-03-15T14:01:49","date_gmt":"2023-03-15T13:01:49","guid":{"rendered":"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/"},"modified":"2026-07-15T06:42:18","modified_gmt":"2026-07-15T04:42:18","slug":"popilia-country-resort","status":"publish","type":"azcompanies","link":"https:\/\/ospitalita-italiana.com\/en\/azcompanies\/popilia-country-resort\/","title":{"rendered":"Popilia Country Resort"},"content":{"rendered":"","protected":false},"featured_media":784817,"template":"","region":[297],"provience":[383],"city":[2991],"tipologias":[2878],"areas":[2881],"class_list":["post-46106","azcompanies","type-azcompanies","status-publish","has-post-thumbnail","hentry","region-calabria","provience-vibo-valentia","city-maierato","tipologias-hotel","areas-dove-dormire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Popilia Country Resort -<\/title>\n<meta name=\"description\" content=\"Popilia Country Resort -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Popilia Country Resort -\" \/>\n<meta property=\"og:description\" content=\"Popilia Country Resort -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T04:42:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/import-company\/16592A.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/\",\"name\":\"Popilia Country Resort -\",\"isPartOf\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\"},\"datePublished\":\"2023-03-15T13:01:49+00:00\",\"dateModified\":\"2026-07-15T04:42:18+00:00\",\"description\":\"Popilia Country Resort -\",\"breadcrumb\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ospitalita-italiana.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Popilia Country Resort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"name\":\"Ospitalit\u00e0 Italiana\",\"description\":\"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ospitalita-italiana.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\",\"name\":\"Isnart\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"contentUrl\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"width\":154,\"height\":126,\"caption\":\"Isnart\"},\"image\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\",\"https:\/\/www.instagram.com\/ospitalitaitaliana_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Popilia Country Resort -","description":"Popilia Country Resort -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/","og_locale":"en_US","og_type":"article","og_title":"Popilia Country Resort -","og_description":"Popilia Country Resort -","og_url":"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/","article_publisher":"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","article_modified_time":"2026-07-15T04:42:18+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/import-company\/16592A.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/","url":"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/","name":"Popilia Country Resort -","isPartOf":{"@id":"https:\/\/ospitalita-italiana.com\/#website"},"datePublished":"2023-03-15T13:01:49+00:00","dateModified":"2026-07-15T04:42:18+00:00","description":"Popilia Country Resort -","breadcrumb":{"@id":"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ospitalita-italiana.com\/azcompanies\/popilia-country-resort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ospitalita-italiana.com\/en\/"},{"@type":"ListItem","position":2,"name":"Popilia Country Resort"}]},{"@type":"WebSite","@id":"https:\/\/ospitalita-italiana.com\/#website","url":"https:\/\/ospitalita-italiana.com\/","name":"Ospitalit\u00e0 Italiana","description":"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0","publisher":{"@id":"https:\/\/ospitalita-italiana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ospitalita-italiana.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ospitalita-italiana.com\/#organization","name":"Isnart","url":"https:\/\/ospitalita-italiana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/","url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","contentUrl":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","width":154,"height":126,"caption":"Isnart"},"image":{"@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","https:\/\/www.instagram.com\/ospitalitaitaliana_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/azcompanies\/46106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/azcompanies"}],"about":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/types\/azcompanies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media\/784817"}],"wp:attachment":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media?parent=46106"}],"wp:term":[{"taxonomy":"region","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/region?post=46106"},{"taxonomy":"provience","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/provience?post=46106"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/city?post=46106"},{"taxonomy":"tipologias","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/tipologias?post=46106"},{"taxonomy":"areas","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/areas?post=46106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}