{"id":1671013,"date":"2026-06-09T04:54:02","date_gmt":"2026-06-09T02:54:02","guid":{"rendered":"https:\/\/ospitalita-italiana.com\/?post_type=worldcompany&#038;p=1671013"},"modified":"2026-07-15T05:10:19","modified_gmt":"2026-07-15T03:10:19","slug":"grappelli-cobham","status":"publish","type":"worldcompany","link":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/grappelli-cobham\/","title":{"rendered":"Grappelli Cobham"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","worldtipologie":[2994],"worldarea":[3015],"worldanation":[2999],"worldcity":[4677,2997],"class_list":["post-1671013","worldcompany","type-worldcompany","status-publish","hentry","worldtipologie-ristoranti","worldarea-europe","worldanation-united-kingdom","worldcity-cobham","worldcity-london"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grappelli Cobham -<\/title>\n<meta name=\"description\" content=\"Grappelli Cobham -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grappelli Cobham -\" \/>\n<meta property=\"og:description\" content=\"Grappelli Cobham -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T03:10:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/\",\"name\":\"Grappelli Cobham -\",\"isPartOf\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\"},\"datePublished\":\"2026-06-09T02:54:02+00:00\",\"dateModified\":\"2026-07-15T03:10:19+00:00\",\"description\":\"Grappelli Cobham -\",\"breadcrumb\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ospitalita-italiana.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grappelli Cobham\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"name\":\"Ospitalit\u00e0 Italiana\",\"description\":\"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ospitalita-italiana.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\",\"name\":\"Isnart\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"contentUrl\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"width\":154,\"height\":126,\"caption\":\"Isnart\"},\"image\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\",\"https:\/\/www.instagram.com\/ospitalitaitaliana_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grappelli Cobham -","description":"Grappelli Cobham -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/","og_locale":"en_US","og_type":"article","og_title":"Grappelli Cobham -","og_description":"Grappelli Cobham -","og_url":"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/","article_publisher":"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","article_modified_time":"2026-07-15T03:10:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/","url":"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/","name":"Grappelli Cobham -","isPartOf":{"@id":"https:\/\/ospitalita-italiana.com\/#website"},"datePublished":"2026-06-09T02:54:02+00:00","dateModified":"2026-07-15T03:10:19+00:00","description":"Grappelli Cobham -","breadcrumb":{"@id":"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ospitalita-italiana.com\/worldcompany\/grappelli-cobham\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ospitalita-italiana.com\/en\/"},{"@type":"ListItem","position":2,"name":"Grappelli Cobham"}]},{"@type":"WebSite","@id":"https:\/\/ospitalita-italiana.com\/#website","url":"https:\/\/ospitalita-italiana.com\/","name":"Ospitalit\u00e0 Italiana","description":"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0","publisher":{"@id":"https:\/\/ospitalita-italiana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ospitalita-italiana.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ospitalita-italiana.com\/#organization","name":"Isnart","url":"https:\/\/ospitalita-italiana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/","url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","contentUrl":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","width":154,"height":126,"caption":"Isnart"},"image":{"@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","https:\/\/www.instagram.com\/ospitalitaitaliana_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany\/1671013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany"}],"about":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/types\/worldcompany"}],"wp:attachment":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media?parent=1671013"}],"wp:term":[{"taxonomy":"worldtipologie","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldtipologie?post=1671013"},{"taxonomy":"worldarea","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldarea?post=1671013"},{"taxonomy":"worldanation","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldanation?post=1671013"},{"taxonomy":"worldcity","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcity?post=1671013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}