{"id":890285,"date":"2025-04-08T04:47:18","date_gmt":"2025-04-08T02:47:18","guid":{"rendered":"https:\/\/ospitalita-italiana.com\/?post_type=worldcompany&#038;p=890285"},"modified":"2026-05-13T05:13:09","modified_gmt":"2026-05-13T03:13:09","slug":"vineataly-enoteca-italiana","status":"publish","type":"worldcompany","link":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/","title":{"rendered":"Vineataly enoteca italiana"},"content":{"rendered":"","protected":false},"featured_media":1817052,"template":"","worldtipologie":[2994],"worldarea":[3022],"worldanation":[3023],"worldcity":[3021],"class_list":["post-890285","worldcompany","type-worldcompany","status-publish","has-post-thumbnail","hentry","worldtipologie-ristoranti","worldarea-oceania","worldanation-australia","worldcity-perth"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vineataly enoteca italiana -<\/title>\n<meta name=\"description\" content=\"Vineataly enoteca italiana -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vineataly enoteca italiana -\" \/>\n<meta property=\"og:description\" content=\"Vineataly enoteca italiana -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T03:13:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2026\/05\/2025_20250115101525_5554_WhatsApp-Image-2025-01-15-at-17.14.06-11.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/\",\"name\":\"Vineataly enoteca italiana -\",\"isPartOf\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\"},\"datePublished\":\"2025-04-08T02:47:18+00:00\",\"dateModified\":\"2026-05-13T03:13:09+00:00\",\"description\":\"Vineataly enoteca italiana -\",\"breadcrumb\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ospitalita-italiana.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vineataly enoteca italiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"name\":\"Ospitalit\u00e0 Italiana\",\"description\":\"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ospitalita-italiana.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\",\"name\":\"Isnart\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"contentUrl\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"width\":154,\"height\":126,\"caption\":\"Isnart\"},\"image\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\",\"https:\/\/www.instagram.com\/ospitalitaitaliana_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vineataly enoteca italiana -","description":"Vineataly enoteca italiana -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/","og_locale":"en_US","og_type":"article","og_title":"Vineataly enoteca italiana -","og_description":"Vineataly enoteca italiana -","og_url":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/","article_publisher":"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","article_modified_time":"2026-05-13T03:13:09+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2026\/05\/2025_20250115101525_5554_WhatsApp-Image-2025-01-15-at-17.14.06-11.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/","url":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/","name":"Vineataly enoteca italiana -","isPartOf":{"@id":"https:\/\/ospitalita-italiana.com\/#website"},"datePublished":"2025-04-08T02:47:18+00:00","dateModified":"2026-05-13T03:13:09+00:00","description":"Vineataly enoteca italiana -","breadcrumb":{"@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/vineataly-enoteca-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ospitalita-italiana.com\/en\/"},{"@type":"ListItem","position":2,"name":"Vineataly enoteca italiana"}]},{"@type":"WebSite","@id":"https:\/\/ospitalita-italiana.com\/#website","url":"https:\/\/ospitalita-italiana.com\/","name":"Ospitalit\u00e0 Italiana","description":"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0","publisher":{"@id":"https:\/\/ospitalita-italiana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ospitalita-italiana.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ospitalita-italiana.com\/#organization","name":"Isnart","url":"https:\/\/ospitalita-italiana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/","url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","contentUrl":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","width":154,"height":126,"caption":"Isnart"},"image":{"@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","https:\/\/www.instagram.com\/ospitalitaitaliana_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany\/890285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany"}],"about":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/types\/worldcompany"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media\/1817052"}],"wp:attachment":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media?parent=890285"}],"wp:term":[{"taxonomy":"worldtipologie","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldtipologie?post=890285"},{"taxonomy":"worldarea","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldarea?post=890285"},{"taxonomy":"worldanation","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldanation?post=890285"},{"taxonomy":"worldcity","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcity?post=890285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}