{"id":948219,"date":"2025-04-05T04:40:27","date_gmt":"2025-04-05T02:40:27","guid":{"rendered":"https:\/\/ospitalita-italiana.com\/?post_type=worldcompany&#038;p=948219"},"modified":"2026-05-13T05:04:58","modified_gmt":"2026-05-13T03:04:58","slug":"italian-artisans","status":"publish","type":"worldcompany","link":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/","title":{"rendered":"Italian Artisans"},"content":{"rendered":"","protected":false},"featured_media":1816894,"template":"","worldtipologie":[3714],"worldarea":[3022],"worldanation":[3023],"worldcity":[3034],"class_list":["post-948219","worldcompany","type-worldcompany","status-publish","has-post-thumbnail","hentry","worldtipologie-pizzerie","worldarea-oceania","worldanation-australia","worldcity-melbourne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Italian Artisans -<\/title>\n<meta name=\"description\" content=\"Italian Artisans -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italian Artisans -\" \/>\n<meta property=\"og:description\" content=\"Italian Artisans -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T03:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2026\/05\/2025_20250120051610_5661_Italian-Artisans-key-image-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"999\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/\",\"name\":\"Italian Artisans -\",\"isPartOf\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\"},\"datePublished\":\"2025-04-05T02:40:27+00:00\",\"dateModified\":\"2026-05-13T03:04:58+00:00\",\"description\":\"Italian Artisans -\",\"breadcrumb\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ospitalita-italiana.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italian Artisans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"name\":\"Ospitalit\u00e0 Italiana\",\"description\":\"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ospitalita-italiana.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\",\"name\":\"Isnart\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"contentUrl\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"width\":154,\"height\":126,\"caption\":\"Isnart\"},\"image\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\",\"https:\/\/www.instagram.com\/ospitalitaitaliana_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Italian Artisans -","description":"Italian Artisans -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/","og_locale":"en_US","og_type":"article","og_title":"Italian Artisans -","og_description":"Italian Artisans -","og_url":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/","article_publisher":"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","article_modified_time":"2026-05-13T03:04:58+00:00","og_image":[{"width":1000,"height":999,"url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2026\/05\/2025_20250120051610_5661_Italian-Artisans-key-image-11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/","url":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/","name":"Italian Artisans -","isPartOf":{"@id":"https:\/\/ospitalita-italiana.com\/#website"},"datePublished":"2025-04-05T02:40:27+00:00","dateModified":"2026-05-13T03:04:58+00:00","description":"Italian Artisans -","breadcrumb":{"@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/italian-artisans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ospitalita-italiana.com\/en\/"},{"@type":"ListItem","position":2,"name":"Italian Artisans"}]},{"@type":"WebSite","@id":"https:\/\/ospitalita-italiana.com\/#website","url":"https:\/\/ospitalita-italiana.com\/","name":"Ospitalit\u00e0 Italiana","description":"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0","publisher":{"@id":"https:\/\/ospitalita-italiana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ospitalita-italiana.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ospitalita-italiana.com\/#organization","name":"Isnart","url":"https:\/\/ospitalita-italiana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/","url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","contentUrl":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","width":154,"height":126,"caption":"Isnart"},"image":{"@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","https:\/\/www.instagram.com\/ospitalitaitaliana_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany\/948219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany"}],"about":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/types\/worldcompany"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media\/1816894"}],"wp:attachment":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media?parent=948219"}],"wp:term":[{"taxonomy":"worldtipologie","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldtipologie?post=948219"},{"taxonomy":"worldarea","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldarea?post=948219"},{"taxonomy":"worldanation","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldanation?post=948219"},{"taxonomy":"worldcity","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcity?post=948219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}