{"id":953331,"date":"2025-04-08T04:40:54","date_gmt":"2025-04-08T02:40:54","guid":{"rendered":"https:\/\/ospitalita-italiana.com\/?post_type=worldcompany&#038;p=953331"},"modified":"2026-05-13T05:03:28","modified_gmt":"2026-05-13T03:03:28","slug":"giro-ditalia-ristorante","status":"publish","type":"worldcompany","link":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/","title":{"rendered":"Giro d&#8217;Italia Ristorante"},"content":{"rendered":"","protected":false},"featured_media":1816850,"template":"","worldtipologie":[2994],"worldarea":[3031],"worldanation":[3055],"worldcity":[4589],"class_list":["post-953331","worldcompany","type-worldcompany","status-publish","has-post-thumbnail","hentry","worldtipologie-ristoranti","worldarea-north-america","worldanation-canada","worldcity-vaughan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Giro d&#039;Italia Ristorante -<\/title>\n<meta name=\"description\" content=\"Giro d&#039;Italia Ristorante -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giro d&#039;Italia Ristorante -\" \/>\n<meta property=\"og:description\" content=\"Giro d&#039;Italia Ristorante -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T03:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2026\/05\/2025_20250201204603_5673_Foto-principale-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"997\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/\",\"name\":\"Giro d'Italia Ristorante -\",\"isPartOf\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\"},\"datePublished\":\"2025-04-08T02:40:54+00:00\",\"dateModified\":\"2026-05-13T03:03:28+00:00\",\"description\":\"Giro d'Italia Ristorante -\",\"breadcrumb\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ospitalita-italiana.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giro d&#8217;Italia Ristorante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#website\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"name\":\"Ospitalit\u00e0 Italiana\",\"description\":\"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0\",\"publisher\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ospitalita-italiana.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#organization\",\"name\":\"Isnart\",\"url\":\"https:\/\/ospitalita-italiana.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"contentUrl\":\"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png\",\"width\":154,\"height\":126,\"caption\":\"Isnart\"},\"image\":{\"@id\":\"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/\",\"https:\/\/www.instagram.com\/ospitalitaitaliana_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giro d'Italia Ristorante -","description":"Giro d'Italia Ristorante -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/","og_locale":"en_US","og_type":"article","og_title":"Giro d'Italia Ristorante -","og_description":"Giro d'Italia Ristorante -","og_url":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/","article_publisher":"https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","article_modified_time":"2026-05-13T03:03:28+00:00","og_image":[{"width":1000,"height":997,"url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2026\/05\/2025_20250201204603_5673_Foto-principale-11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/","url":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/","name":"Giro d'Italia Ristorante -","isPartOf":{"@id":"https:\/\/ospitalita-italiana.com\/#website"},"datePublished":"2025-04-08T02:40:54+00:00","dateModified":"2026-05-13T03:03:28+00:00","description":"Giro d'Italia Ristorante -","breadcrumb":{"@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ospitalita-italiana.com\/en\/worldcompany\/giro-ditalia-ristorante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ospitalita-italiana.com\/en\/"},{"@type":"ListItem","position":2,"name":"Giro d&#8217;Italia Ristorante"}]},{"@type":"WebSite","@id":"https:\/\/ospitalita-italiana.com\/#website","url":"https:\/\/ospitalita-italiana.com\/","name":"Ospitalit\u00e0 Italiana","description":"L\u2019 ospitalit\u00e0 che meriti - destinAzioni e strutture di qualit\u00e0","publisher":{"@id":"https:\/\/ospitalita-italiana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ospitalita-italiana.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ospitalita-italiana.com\/#organization","name":"Isnart","url":"https:\/\/ospitalita-italiana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/","url":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","contentUrl":"https:\/\/ospitalita-italiana.com\/wp-content\/uploads\/2022\/04\/header-logo.png","width":154,"height":126,"caption":"Isnart"},"image":{"@id":"https:\/\/ospitalita-italiana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MarchiodiQualitaOspitalitaItaliana\/","https:\/\/www.instagram.com\/ospitalitaitaliana_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany\/953331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcompany"}],"about":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/types\/worldcompany"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media\/1816850"}],"wp:attachment":[{"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/media?parent=953331"}],"wp:term":[{"taxonomy":"worldtipologie","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldtipologie?post=953331"},{"taxonomy":"worldarea","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldarea?post=953331"},{"taxonomy":"worldanation","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldanation?post=953331"},{"taxonomy":"worldcity","embeddable":true,"href":"https:\/\/ospitalita-italiana.com\/en\/wp-json\/wp\/v2\/worldcity?post=953331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}